{"id":306,"date":"2019-11-29T11:46:21","date_gmt":"2019-11-29T10:46:21","guid":{"rendered":"http:\/\/www2.wmt.it\/?page_id=306"},"modified":"2019-12-20T15:03:57","modified_gmt":"2019-12-20T14:03:57","slug":"servizi","status":"publish","type":"page","link":"http:\/\/www.wmt.it\/index.php\/servizi\/","title":{"rendered":"Servizi"},"content":{"rendered":"\n<p>W.M.T. \u00e9 in grado di offrire alla sua clientela un&#8217;ampia gamma di servizi quali:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><a href=\"http:\/\/www2.wmt.it\/index.php\/laboratorio-chimico-fisico-di-ricerca-e-sviluppo\/\">analisi chimico\/fisiche su acque e liquidi industriali<\/a>;<\/li><li>ingegneria:<ul><li>progetto di fattibilit\u00e1,<\/li><li>progetto esecutivo,<\/li><li>stesura delle specifiche di realizzazione;<\/li><\/ul><\/li><li>cura della realizzazione (quando affidata a terzi):<ul><li>direzione lavori,<\/li><li>collaudi;<\/li><\/ul><\/li><li>realizzazione del progetto,<\/li><li>messa in marcia dell&#8217;impianto,<\/li><li>istruzione del personale preposto alla gestione,<\/li><li>assistenza post vendita realizzata:<ul><li>sul luogo di installazione,<\/li><li>remotata in sede attraverso sistemi di teleservice.<\/li><\/ul><\/li><\/ul>\n","protected":false},"excerpt":{"rendered":"<p>W.M.T. \u00e9 in grado di offrire alla sua clientela un&#8217;ampia gamma di servizi quali: analisi chimico\/fisiche su acque e liquidi industriali; ingegneria: progetto di fattibilit\u00e1, progetto esecutivo, stesura delle specifiche di realizzazione; cura della realizzazione (quando affidata a terzi): direzione lavori, collaudi; realizzazione del progetto, messa in marcia dell&#8217;impianto, istruzione del personale preposto alla gestione, [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":1760,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"ngg_post_thumbnail":0,"footnotes":""},"class_list":["post-306","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Servizi &#8226; W.M.T. - Water and Mechanical Technology s.r.l.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/www.wmt.it\/index.php\/servizi\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Servizi &#8226; W.M.T. - Water and Mechanical Technology s.r.l.\" \/>\n<meta property=\"og:description\" content=\"W.M.T. \u00e9 in grado di offrire alla sua clientela un&#8217;ampia gamma di servizi quali: analisi chimico\/fisiche su acque e liquidi industriali; ingegneria: progetto di fattibilit\u00e1, progetto esecutivo, stesura delle specifiche di realizzazione; cura della realizzazione (quando affidata a terzi): direzione lavori, collaudi; realizzazione del progetto, messa in marcia dell&#8217;impianto, istruzione del personale preposto alla gestione, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"http:\/\/www.wmt.it\/index.php\/servizi\/\" \/>\n<meta property=\"og:site_name\" content=\"W.M.T. - Water and Mechanical Technology s.r.l.\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/pages\/WMT\/523330841079249?eid=ARBCva1bxbHrIwpLi2jUbikM5NzJrQOywcEqrkgUjYQ_m59R20SghP76Um2Ffw8jsoHFxRwr_28Y5a6v\" \/>\n<meta property=\"article:modified_time\" content=\"2019-12-20T14:03:57+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.wmt.it\/wp-content\/uploads\/2019\/12\/custom-\u2013-1-e1576747198947.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/www.wmt.it\\\/index.php\\\/servizi\\\/\",\"url\":\"http:\\\/\\\/www.wmt.it\\\/index.php\\\/servizi\\\/\",\"name\":\"Servizi &#8226; W.M.T. - Water and Mechanical Technology s.r.l.\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/www.wmt.it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\\\/\\\/www.wmt.it\\\/index.php\\\/servizi\\\/#primaryimage\"},\"image\":{\"@id\":\"http:\\\/\\\/www.wmt.it\\\/index.php\\\/servizi\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.wmt.it\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/custom-\u2013-1-e1576747198947.jpg\",\"datePublished\":\"2019-11-29T10:46:21+00:00\",\"dateModified\":\"2019-12-20T14:03:57+00:00\",\"breadcrumb\":{\"@id\":\"http:\\\/\\\/www.wmt.it\\\/index.php\\\/servizi\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/www.wmt.it\\\/index.php\\\/servizi\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"http:\\\/\\\/www.wmt.it\\\/index.php\\\/servizi\\\/#primaryimage\",\"url\":\"http:\\\/\\\/www.wmt.it\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/custom-\u2013-1-e1576747198947.jpg\",\"contentUrl\":\"http:\\\/\\\/www.wmt.it\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/custom-\u2013-1-e1576747198947.jpg\",\"width\":1920,\"height\":600},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/www.wmt.it\\\/index.php\\\/servizi\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"http:\\\/\\\/www.wmt.it\\\/index.php\\\/en\\\/wmt-home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Servizi\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/www.wmt.it\\\/#website\",\"url\":\"http:\\\/\\\/www.wmt.it\\\/\",\"name\":\"W.M.T. - Water and Mechanical Technology s.r.l.\",\"description\":\"ENGINEERING AND FILTERING SYSTEM, PURE WITH PROFIT\",\"publisher\":{\"@id\":\"http:\\\/\\\/www.wmt.it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/www.wmt.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"http:\\\/\\\/www.wmt.it\\\/#organization\",\"name\":\"W.M.T. - Water and Mechanical Technology s.r.l.\",\"url\":\"http:\\\/\\\/www.wmt.it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"http:\\\/\\\/www.wmt.it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/www.wmt.it\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/logo_wmt_blu_512x512.jpg\",\"contentUrl\":\"http:\\\/\\\/www.wmt.it\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/logo_wmt_blu_512x512.jpg\",\"width\":512,\"height\":512,\"caption\":\"W.M.T. - Water and Mechanical Technology s.r.l.\"},\"image\":{\"@id\":\"http:\\\/\\\/www.wmt.it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/pages\\\/WMT\\\/523330841079249?eid=ARBCva1bxbHrIwpLi2jUbikM5NzJrQOywcEqrkgUjYQ_m59R20SghP76Um2Ffw8jsoHFxRwr_28Y5a6v\",\"https:\\\/\\\/www.google.com\\\/maps\\\/place\\\/W.M.T.+-+Water+and+Mechanical+Technology+s.r.l.\\\/@45.538948,9.1806583,17z\\\/data=!3m1!4b1!4m5!3m4!1s0x4786bf60c912a84b:0xfc12749d2f8ea14a!8m2!3d45.538948!4d9.182847\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/2059941\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Servizi &#8226; W.M.T. - Water and Mechanical Technology s.r.l.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/www.wmt.it\/index.php\/servizi\/","og_locale":"it_IT","og_type":"article","og_title":"Servizi &#8226; W.M.T. - Water and Mechanical Technology s.r.l.","og_description":"W.M.T. \u00e9 in grado di offrire alla sua clientela un&#8217;ampia gamma di servizi quali: analisi chimico\/fisiche su acque e liquidi industriali; ingegneria: progetto di fattibilit\u00e1, progetto esecutivo, stesura delle specifiche di realizzazione; cura della realizzazione (quando affidata a terzi): direzione lavori, collaudi; realizzazione del progetto, messa in marcia dell&#8217;impianto, istruzione del personale preposto alla gestione, [&hellip;]","og_url":"http:\/\/www.wmt.it\/index.php\/servizi\/","og_site_name":"W.M.T. - Water and Mechanical Technology s.r.l.","article_publisher":"https:\/\/www.facebook.com\/pages\/WMT\/523330841079249?eid=ARBCva1bxbHrIwpLi2jUbikM5NzJrQOywcEqrkgUjYQ_m59R20SghP76Um2Ffw8jsoHFxRwr_28Y5a6v","article_modified_time":"2019-12-20T14:03:57+00:00","og_image":[{"width":1920,"height":600,"url":"http:\/\/www.wmt.it\/wp-content\/uploads\/2019\/12\/custom-\u2013-1-e1576747198947.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"http:\/\/www.wmt.it\/index.php\/servizi\/","url":"http:\/\/www.wmt.it\/index.php\/servizi\/","name":"Servizi &#8226; W.M.T. - Water and Mechanical Technology s.r.l.","isPartOf":{"@id":"http:\/\/www.wmt.it\/#website"},"primaryImageOfPage":{"@id":"http:\/\/www.wmt.it\/index.php\/servizi\/#primaryimage"},"image":{"@id":"http:\/\/www.wmt.it\/index.php\/servizi\/#primaryimage"},"thumbnailUrl":"http:\/\/www.wmt.it\/wp-content\/uploads\/2019\/12\/custom-\u2013-1-e1576747198947.jpg","datePublished":"2019-11-29T10:46:21+00:00","dateModified":"2019-12-20T14:03:57+00:00","breadcrumb":{"@id":"http:\/\/www.wmt.it\/index.php\/servizi\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["http:\/\/www.wmt.it\/index.php\/servizi\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"http:\/\/www.wmt.it\/index.php\/servizi\/#primaryimage","url":"http:\/\/www.wmt.it\/wp-content\/uploads\/2019\/12\/custom-\u2013-1-e1576747198947.jpg","contentUrl":"http:\/\/www.wmt.it\/wp-content\/uploads\/2019\/12\/custom-\u2013-1-e1576747198947.jpg","width":1920,"height":600},{"@type":"BreadcrumbList","@id":"http:\/\/www.wmt.it\/index.php\/servizi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"http:\/\/www.wmt.it\/index.php\/en\/wmt-home\/"},{"@type":"ListItem","position":2,"name":"Servizi"}]},{"@type":"WebSite","@id":"http:\/\/www.wmt.it\/#website","url":"http:\/\/www.wmt.it\/","name":"W.M.T. - Water and Mechanical Technology s.r.l.","description":"ENGINEERING AND FILTERING SYSTEM, PURE WITH PROFIT","publisher":{"@id":"http:\/\/www.wmt.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/www.wmt.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"http:\/\/www.wmt.it\/#organization","name":"W.M.T. - Water and Mechanical Technology s.r.l.","url":"http:\/\/www.wmt.it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"http:\/\/www.wmt.it\/#\/schema\/logo\/image\/","url":"http:\/\/www.wmt.it\/wp-content\/uploads\/2019\/12\/logo_wmt_blu_512x512.jpg","contentUrl":"http:\/\/www.wmt.it\/wp-content\/uploads\/2019\/12\/logo_wmt_blu_512x512.jpg","width":512,"height":512,"caption":"W.M.T. - Water and Mechanical Technology s.r.l."},"image":{"@id":"http:\/\/www.wmt.it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/pages\/WMT\/523330841079249?eid=ARBCva1bxbHrIwpLi2jUbikM5NzJrQOywcEqrkgUjYQ_m59R20SghP76Um2Ffw8jsoHFxRwr_28Y5a6v","https:\/\/www.google.com\/maps\/place\/W.M.T.+-+Water+and+Mechanical+Technology+s.r.l.\/@45.538948,9.1806583,17z\/data=!3m1!4b1!4m5!3m4!1s0x4786bf60c912a84b:0xfc12749d2f8ea14a!8m2!3d45.538948!4d9.182847","https:\/\/www.linkedin.com\/company\/2059941"]}]}},"_links":{"self":[{"href":"http:\/\/www.wmt.it\/index.php\/wp-json\/wp\/v2\/pages\/306","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.wmt.it\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"http:\/\/www.wmt.it\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"http:\/\/www.wmt.it\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"http:\/\/www.wmt.it\/index.php\/wp-json\/wp\/v2\/comments?post=306"}],"version-history":[{"count":2,"href":"http:\/\/www.wmt.it\/index.php\/wp-json\/wp\/v2\/pages\/306\/revisions"}],"predecessor-version":[{"id":1864,"href":"http:\/\/www.wmt.it\/index.php\/wp-json\/wp\/v2\/pages\/306\/revisions\/1864"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.wmt.it\/index.php\/wp-json\/wp\/v2\/media\/1760"}],"wp:attachment":[{"href":"http:\/\/www.wmt.it\/index.php\/wp-json\/wp\/v2\/media?parent=306"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}