{"id":3781,"date":"2025-03-05T16:21:21","date_gmt":"2025-03-05T15:21:21","guid":{"rendered":"http:\/\/www.wmt.it\/?page_id=3781"},"modified":"2025-03-06T16:13:43","modified_gmt":"2025-03-06T15:13:43","slug":"separatori-bifasici-e-trifasici-c-p-i-corrugate-plate-interceptor","status":"publish","type":"page","link":"http:\/\/www.wmt.it\/index.php\/separatori-bifasici-e-trifasici-c-p-i-corrugate-plate-interceptor\/","title":{"rendered":"Separatori bifasici e trifasici, C.P.I. &#8211; Corrugate Plate Interceptor"},"content":{"rendered":"\n<p class=\"has-medium-font-size\"><strong><br>SEPARATORI A PACCHI LAMELLARI &#8211; C.P.I.<\/strong><\/p>\n\n\n\n<p>Il separatore a pacchi lamellari, di seguito C.P.I., \u00e8 un dispositivo atto a separare particelle immiscibili contenute in un corpo fluido quando queste abbiano un diverso peso specifico rispetto al corpo fluido stesso.<\/p>\n\n\n\n<p>In tale evenienza i corpi fluidi multi-fase, solido-liquido o liquido-liquido, possono essere separati meccanicamente per effetto della forza di gravit\u00e0 per mezzo del naturale effetto:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>di sedimentazione, nel caso in cui le particelle presenti abbiano una densit\u00e0 maggiore del corpo fluido, in questo caso il C.P.I. viene considerato come un vero e proprio sedimentatore statico;<\/li>\n\n\n\n<li>di flottazione, nel caso in cui le particelle presenti abbiano una densit\u00e0 minore del corpo fluido, in questo caso il C.P.I. viene considerato come un vero e proprio flottatore statico come ad esempio un disoleatore.<\/li>\n<\/ul>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"alignright size-large is-resized\"><img fetchpriority=\"high\" decoding=\"async\" width=\"700\" height=\"656\" src=\"http:\/\/www.wmt.it\/wp-content\/uploads\/2025\/03\/cpi-3d-700x656.png\" alt=\"\" class=\"wp-image-3782\" style=\"width:280px;height:auto\" srcset=\"http:\/\/www.wmt.it\/wp-content\/uploads\/2025\/03\/cpi-3d-700x656.png 700w, http:\/\/www.wmt.it\/wp-content\/uploads\/2025\/03\/cpi-3d-300x281.png 300w, http:\/\/www.wmt.it\/wp-content\/uploads\/2025\/03\/cpi-3d-768x720.png 768w, http:\/\/www.wmt.it\/wp-content\/uploads\/2025\/03\/cpi-3d.png 951w\" sizes=\"(max-width: 700px) 100vw, 700px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"has-medium-font-size\"><strong>FUNZIONAMENTO DEL SEPARATORE A LAMELLE ONDULATE<\/strong><\/p>\n\n\n\n<p>L\u2019elevata efficienza del C.P.I., \u00e8 garantita dall\u2019utilizzo di lamelle ondulate a piani paralleli con canali collettori indipendenti.<\/p>\n\n\n\n<p>In questa configurazione le particelle immiscibili non devono pi\u00f9 salire fino alla superficie della vasca oppure precipitare fino al fondo come avviene nei convenzionali separatori nelle vasche di flottazione o di decantazione. Con questa configurazione ogni particella immiscibile deve percorrere solamente la breve distanza tra le lamelle ondulate formanti i due piani attigui.<\/p>\n\n\n\n<p>L&#8217;inclinazione delle lamelle rispetto la vena fluida assicura poi una migliore raccolta e favorisce l&#8217;avvio delle particelle inquinanti gi\u00e0 separatesi dal corpo fluido.<br>Infine, i canali collettori, posizionati sia all&#8217;entrata sia all&#8217;uscita delle pacco lamellare, raccolgono le sostanze separate senza incontrare ostacoli e senza subire ulteriori turbolenze date dalla corrente del corpo fluido.<\/p>\n\n\n\n<p class=\"has-medium-font-size\"><strong>PERCORSO DEL CORPO FLUIDO NEL C.P.I. CON FUNZIONE DI SEDIMENTATORE<\/strong><\/p>\n\n\n\n<p class=\"has-medium-font-size\"><strong>PERCORSO &#8220;A&#8221;<\/strong><\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"alignright size-large is-resized\"><img decoding=\"async\" width=\"700\" height=\"549\" src=\"http:\/\/www.wmt.it\/wp-content\/uploads\/2025\/03\/cpi-percorsi-700x549.png\" alt=\"\" class=\"wp-image-3785\" style=\"width:602px;height:auto\" srcset=\"http:\/\/www.wmt.it\/wp-content\/uploads\/2025\/03\/cpi-percorsi-700x549.png 700w, http:\/\/www.wmt.it\/wp-content\/uploads\/2025\/03\/cpi-percorsi-300x235.png 300w, http:\/\/www.wmt.it\/wp-content\/uploads\/2025\/03\/cpi-percorsi.png 744w\" sizes=\"(max-width: 700px) 100vw, 700px\" \/><\/figure>\n<\/div>\n\n\n<p>Durante la depurazione del corpo fluido inquinato da particelle con una densit\u00e0 maggiore del corpo fluido, il flusso scorre nel pacco lamellare dal basso verso l&#8217;alto; le particelle solide si raccolgono sulle superfici superiori delle lamelle ondulate e scorrono in controcorrente fino ai canali collettori inferiori in virt\u00f9 della inclinazione a 45\u00b0 del pacco; una volta raccolti da questi precipitano quindi sul fondo della vasca oppure nella tramoggia fanghi.<\/p>\n\n\n\n<p class=\"has-medium-font-size\"><strong>PERCORSO DEL CORPO FLUIDO NEL C.P.I. CON FUNZIONE DI FLOTTATORE<\/strong><\/p>\n\n\n\n<p class=\"has-medium-font-size\"><strong>PERCORSO &#8220;B&#8221;<\/strong><\/p>\n\n\n\n<p>Il corpo fluido entra nel pacco lamellare dall&#8217;alto: il pacco ha una inclinazione di 45\u00b0.<\/p>\n\n\n\n<p>Il flusso tra i piani lamellari \u00e8 laminare. Nel loro moto ascendente le particelle, contenute nel corpo fluido con peso specifico inferiore al corpo fluido stesso, salgono in controcorrente al flusso senza incontrare ostacoli fino a raggiungere la parte inferiore della lamella sovrastante, quindi proseguono la risalita verso i canali collettori sistemati anteriormente alla sommit\u00e0 delle lamelle ondulate e da questi risalgono raggiungendo la superficie della vasca.<\/p>\n\n\n\n<p>Le eventuali particelle, contenute nel corpo fluido con peso specifico superiore al corpo fluido stesso, si depositano nell&#8217;incavo inferiore della lamella sottostante, quindi precipitano, trasportati dal flusso della corrente, fino all&#8217;uscita del pacco dove vengono raccolte nei canali collettori e convogliate verso il fondo della vasca, oppure nella tramoggia fanghi.<\/p>\n\n\n\n<p class=\"has-medium-font-size\"><strong>DA &#8220;C&#8221;<\/strong><\/p>\n\n\n\n<p>si scaricano le sostanze flottate.<\/p>\n\n\n\n<p class=\"has-medium-font-size\"><strong>DA &#8220;D&#8221;<\/strong><\/p>\n\n\n\n<p>si scaricano le sostanze sedimentate.<\/p>\n\n\n\n<p><br>Il separatore pu\u00f2 funzionare, indipendentemente dalla posizione d\u2019alimentazione data dal percorso &#8220;A&#8221; o &#8220;B&#8221;, con rendimenti leggermente inferiori.<\/p>\n\n\n\n<p>Il rendimento complessivo del sistema \u00e8 variabile tra l\u201985% ed il 99 %.<\/p>\n\n\n\n<p class=\"has-medium-font-size\"><strong>VARIANTI<\/strong><\/p>\n\n\n\n<p class=\"has-medium-font-size\"><strong>SEPARATORI TRIFASICI<\/strong><\/p>\n\n\n\n<p>Qualora il corpo fluido da trattare inglobi aeriformi i C.P.I. possono essere inseriti in serbatoi cilindrici a chiusura ermetica.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"700\" height=\"495\" data-id=\"3790\" src=\"http:\/\/www.wmt.it\/wp-content\/uploads\/2025\/03\/cpi3faseinglese-700x495.jpg\" alt=\"\" class=\"wp-image-3790\" srcset=\"http:\/\/www.wmt.it\/wp-content\/uploads\/2025\/03\/cpi3faseinglese-700x495.jpg 700w, http:\/\/www.wmt.it\/wp-content\/uploads\/2025\/03\/cpi3faseinglese-300x212.jpg 300w, http:\/\/www.wmt.it\/wp-content\/uploads\/2025\/03\/cpi3faseinglese-768x543.jpg 768w, http:\/\/www.wmt.it\/wp-content\/uploads\/2025\/03\/cpi3faseinglese-1536x1086.jpg 1536w, http:\/\/www.wmt.it\/wp-content\/uploads\/2025\/03\/cpi3faseinglese-2048x1448.jpg 2048w\" sizes=\"(max-width: 700px) 100vw, 700px\" \/><figcaption class=\"wp-element-caption\"><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-black-color\">Schema di separatore trifasico.<\/mark><\/strong><\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"272\" height=\"185\" data-id=\"3789\" src=\"http:\/\/www.wmt.it\/wp-content\/uploads\/2025\/03\/tps_01.jpg\" alt=\"\" class=\"wp-image-3789\"\/><\/figure>\n<\/figure>\n\n\n\n<p>In questo caso il complesso, oltre a separare le particelle contenute nel corpo fluido con peso specifico inferiore o superiore al corpo fluido stesso, separa anche gli aeriformi contenuti nel corpo fluido da trattare.<\/p>\n\n\n\n<p class=\"has-medium-font-size\"><strong>VANTAGGI DEL C.P.I.<\/strong><\/p>\n\n\n\n<p>Massima superficie utile con un minimo volume impiegato.<br>La limitata esigenza d\u2019area consente installazioni in luoghi non adeguati alla costruzione di impianti convenzionali.<br>Possibilit\u00e0 di separazione di sostanze inquinanti con un piccolo impianto con vasca comune: affinch\u00e9 avvenga la separazione e quindi la depurazione del corpo fluido dalle sostanze inquinanti, queste devono percorrere solo la breve distanza tra le due superfici ondulate formanti il pacco lamellare. Di conseguenza si raggiungono rendimentistraordinariamente alti con notevoli potenzialit\u00e0 in un minimo spazio.<br>Costi d\u2019esercizio limitati.<br>Manutenzione praticamente nulla.<br>Esercizio continuo.<br>Nessun organo in movimento.<br>Unit\u00e0 compatta.<br>Semplice installazione.<br>Insensibilit\u00e0 alle variazioni di portata.<\/p>\n\n\n\n<p class=\"has-medium-font-size\"><strong>SETTORI D\u2019IMPIEGO<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li> Industria petrolifera e petrolchimica.<\/li>\n\n\n\n<li>Depositi lubrificanti.<\/li>\n\n\n\n<li>Impianti per acqua potabile.<\/li>\n\n\n\n<li>Stazioni di servizio.<\/li>\n\n\n\n<li>Aeroporti.<\/li>\n\n\n\n<li>Navi.<\/li>\n\n\n\n<li>Industria alimentare.<\/li>\n\n\n\n<li>Industria dello zucchero.<\/li>\n\n\n\n<li>Industria tessile.<\/li>\n\n\n\n<li>Industria siderurgica<\/li>\n\n\n\n<li>Industria estrattiva.<\/li>\n\n\n\n<li>Cave e cementifici.<\/li>\n\n\n\n<li>Industria della plastica.<\/li>\n<\/ul>\n\n\n\n<p class=\"has-medium-font-size\"><strong>TIPOLOGIE DI FORNITURA<\/strong><\/p>\n\n\n\n<div class=\"wp-block-media-text is-stacked-on-mobile\" style=\"grid-template-columns:31% auto\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"259\" height=\"194\" src=\"http:\/\/www.wmt.it\/wp-content\/uploads\/2025\/03\/cpi_07.jpg\" alt=\"\" class=\"wp-image-3803 size-full\"\/><\/figure><div class=\"wp-block-media-text__content\">\n<p>Pacchi lamellari.<\/p>\n\n\n\n<p>Fornibili in diversi materiali, quali:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Plastiche\n<ul class=\"wp-block-list\">\n<li>Polietilene<\/li>\n\n\n\n<li>Polipropilene<\/li>\n\n\n\n<li>Teflon<\/li>\n<\/ul>\n<\/li>\n\n\n\n<li>Acciai\n<ul class=\"wp-block-list\">\n<li>acciai al corbonio<\/li>\n\n\n\n<li>acciai inossidabili<\/li>\n<\/ul>\n<\/li>\n\n\n\n<li>Leghe\n<ul class=\"wp-block-list\">\n<li>Monel<\/li>\n\n\n\n<li>Hastelloy<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<\/div><\/div>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-2 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"247\" height=\"204\" data-id=\"3806\" src=\"http:\/\/www.wmt.it\/wp-content\/uploads\/2025\/03\/cpi_01-1.jpg\" alt=\"\" class=\"wp-image-3806\"\/><figcaption class=\"wp-element-caption\"><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-black-color\">Disegni del profilo della vasca con installazione in vasca di cemento o in vasca d\u2019acciaio.<\/mark><\/strong><\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"247\" height=\"204\" data-id=\"3807\" src=\"http:\/\/www.wmt.it\/wp-content\/uploads\/2025\/03\/cpi_02.jpg\" alt=\"\" class=\"wp-image-3807\"\/><figcaption class=\"wp-element-caption\"><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-black-color\"><strong>Separatore completo di vasca e pacchi lamellari.<\/strong><\/mark><\/figcaption><\/figure>\n<\/figure>\n\n\n\n<div class=\"wp-block-media-text is-stacked-on-mobile is-vertically-aligned-bottom\" style=\"grid-template-columns:25% auto\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"184\" height=\"138\" src=\"http:\/\/www.wmt.it\/wp-content\/uploads\/2025\/03\/cpi_03.jpg\" alt=\"\" class=\"wp-image-3812 size-full\"\/><\/figure><div class=\"wp-block-media-text__content\">\n<p><br>Separatori compositi con funzione di flottazione e sedimentazione.<\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-media-text has-media-on-the-right is-stacked-on-mobile is-vertically-aligned-bottom\"><div class=\"wp-block-media-text__content\">\n<p>Moduli di separatori multipli, in base alle esigenze di flusso del sistema, con o senza accessori, incluso o escluso il montaggio.<\/p>\n<\/div><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"259\" height=\"194\" src=\"http:\/\/www.wmt.it\/wp-content\/uploads\/2025\/03\/cpi_06.jpg\" alt=\"\" class=\"wp-image-3813 size-full\"\/><\/figure><\/div>\n\n\n\n<div class=\"wp-block-media-text is-stacked-on-mobile is-vertically-aligned-bottom\" style=\"grid-template-columns:25% auto\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"177\" height=\"136\" src=\"http:\/\/www.wmt.it\/wp-content\/uploads\/2025\/03\/cpi_04.jpg\" alt=\"\" class=\"wp-image-3814 size-full\"\/><\/figure><div class=\"wp-block-media-text__content\">\n<p>Sistemi ausiliari per la rimozione del surnatante flottato.<br>Sistemi ausiliari per la rimozione dei fanghi sedimentati.<\/p>\n<\/div><\/div>\n\n\n\n<table style=\"width: 100%;\" cellspacing=\"0\" border=\"0\">\n\t<tbody>\n\t\t<tr>\n\t\t\t<td style=\"width: 10%;\" align=\"center\"><\/td>\n\t\t\t<td style=\"width: 35%;\" align=\"center\"><\/td>\n\t\t\t<td style=\"width: 10%;\" align=\"center\"><\/td>\n\t\t\t<td style=\"width: 35%;\" align=\"center\"><div class=\"wp-block-button\"><a class=\"wp-block-button__link has-background has-vivid-cyan-blue-background-color\" href=\"http:\/\/www.wmt.it\/wp-content\/uploads\/2025\/03\/WMT_19_CPI_IT_2025_A4.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">Scarica la brochure<\/a><\/div><\/td>\n\t\t\t<td style=\"width: 10%;\" align=\"center\"><\/td>\n\t\t<\/tr>\n\t<\/tbody>\n<\/table>\n\n\n\n<p>Per qualsiasi informazione e configurazione riguardante: separatori bifasici e trifasici, C.P.I. &#8211; Corrugate Plate Interceptor, in grado di soddisfare le vostre specifiche esigenze, siete pregati di contattare il nostro&nbsp;<a href=\"mailto:dip@wmt.it?subject=Richiesta%20di%20chiarimenti%20per%20separatori%20bifasici%20e%20trifasici,%20C.P.I.\">ufficio tecnico<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>SEPARATORI A PACCHI LAMELLARI &#8211; C.P.I. Il separatore a pacchi lamellari, di seguito C.P.I., \u00e8 un dispositivo atto a separare particelle immiscibili contenute in un corpo fluido quando queste abbiano un diverso peso specifico rispetto al corpo fluido stesso. In tale evenienza i corpi fluidi multi-fase, solido-liquido o liquido-liquido, possono essere separati meccanicamente per effetto [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":3887,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"ngg_post_thumbnail":0,"footnotes":""},"class_list":["post-3781","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Separatori bifasici e trifasici, C.P.I. - Corrugate Plate Interceptor &#8226; W.M.T. - Water and Mechanical Technology s.r.l.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/www.wmt.it\/index.php\/separatori-bifasici-e-trifasici-c-p-i-corrugate-plate-interceptor\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Separatori bifasici e trifasici, C.P.I. - Corrugate Plate Interceptor &#8226; W.M.T. - Water and Mechanical Technology s.r.l.\" \/>\n<meta property=\"og:description\" content=\"SEPARATORI A PACCHI LAMELLARI &#8211; C.P.I. Il separatore a pacchi lamellari, di seguito C.P.I., \u00e8 un dispositivo atto a separare particelle immiscibili contenute in un corpo fluido quando queste abbiano un diverso peso specifico rispetto al corpo fluido stesso. In tale evenienza i corpi fluidi multi-fase, solido-liquido o liquido-liquido, possono essere separati meccanicamente per effetto [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"http:\/\/www.wmt.it\/index.php\/separatori-bifasici-e-trifasici-c-p-i-corrugate-plate-interceptor\/\" \/>\n<meta property=\"og:site_name\" content=\"W.M.T. - Water and Mechanical Technology s.r.l.\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/pages\/WMT\/523330841079249?eid=ARBCva1bxbHrIwpLi2jUbikM5NzJrQOywcEqrkgUjYQ_m59R20SghP76Um2Ffw8jsoHFxRwr_28Y5a6v\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-06T15:13:43+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.wmt.it\/wp-content\/uploads\/2025\/03\/cpi_front_image-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1892\" \/>\n\t<meta property=\"og:image:height\" content=\"582\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"7 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/www.wmt.it\\\/index.php\\\/separatori-bifasici-e-trifasici-c-p-i-corrugate-plate-interceptor\\\/\",\"url\":\"http:\\\/\\\/www.wmt.it\\\/index.php\\\/separatori-bifasici-e-trifasici-c-p-i-corrugate-plate-interceptor\\\/\",\"name\":\"Separatori bifasici e trifasici, C.P.I. - Corrugate Plate Interceptor &#8226; W.M.T. - Water and Mechanical Technology s.r.l.\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/www.wmt.it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\\\/\\\/www.wmt.it\\\/index.php\\\/separatori-bifasici-e-trifasici-c-p-i-corrugate-plate-interceptor\\\/#primaryimage\"},\"image\":{\"@id\":\"http:\\\/\\\/www.wmt.it\\\/index.php\\\/separatori-bifasici-e-trifasici-c-p-i-corrugate-plate-interceptor\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.wmt.it\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/cpi_front_image-2.jpg\",\"datePublished\":\"2025-03-05T15:21:21+00:00\",\"dateModified\":\"2025-03-06T15:13:43+00:00\",\"breadcrumb\":{\"@id\":\"http:\\\/\\\/www.wmt.it\\\/index.php\\\/separatori-bifasici-e-trifasici-c-p-i-corrugate-plate-interceptor\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/www.wmt.it\\\/index.php\\\/separatori-bifasici-e-trifasici-c-p-i-corrugate-plate-interceptor\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"http:\\\/\\\/www.wmt.it\\\/index.php\\\/separatori-bifasici-e-trifasici-c-p-i-corrugate-plate-interceptor\\\/#primaryimage\",\"url\":\"http:\\\/\\\/www.wmt.it\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/cpi_front_image-2.jpg\",\"contentUrl\":\"http:\\\/\\\/www.wmt.it\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/cpi_front_image-2.jpg\",\"width\":1892,\"height\":582,\"caption\":\"File Name : DSCN0003.JPG File Size : 181.1KB (185430 Bytes) Date Taken : 0000\\\/00\\\/00 00:00:00 Image Size : 1024 x 768 pixels Resolution : 300 x 300 dpi Bit Depth : 8 bits\\\/channel Protection Attribute : Off Hide Attribute : Off Camera ID : N\\\/A Camera : E885 Quality Mode : NORMAL Metering Mode : Matrix Exposure Mode : Programmed Auto Speed Light : Yes Focal Length : 8 mm Shutter Speed : 1\\\/60 second Aperture : F2.8 Exposure Compensation : 0 EV White Balance : Auto Lens : Built-in Flash Sync Mode : Normal Exposure Difference : N\\\/A Flexible Program : N\\\/A Sensitivity : Auto Sharpening : Auto Image Type : Color Color Mode : N\\\/A Hue Adjustment : N\\\/A Saturation Control : Normal Tone Compensation : Auto Latitude(GPS) : N\\\/A Longitude(GPS) : N\\\/A Altitude(GPS) : N\\\/A\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/www.wmt.it\\\/index.php\\\/separatori-bifasici-e-trifasici-c-p-i-corrugate-plate-interceptor\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"http:\\\/\\\/www.wmt.it\\\/index.php\\\/en\\\/wmt-home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Separatori bifasici e trifasici, C.P.I. &#8211; Corrugate Plate Interceptor\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/www.wmt.it\\\/#website\",\"url\":\"http:\\\/\\\/www.wmt.it\\\/\",\"name\":\"W.M.T. - Water and Mechanical Technology s.r.l.\",\"description\":\"ENGINEERING AND FILTERING SYSTEM, PURE WITH PROFIT\",\"publisher\":{\"@id\":\"http:\\\/\\\/www.wmt.it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/www.wmt.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"http:\\\/\\\/www.wmt.it\\\/#organization\",\"name\":\"W.M.T. - Water and Mechanical Technology s.r.l.\",\"url\":\"http:\\\/\\\/www.wmt.it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"http:\\\/\\\/www.wmt.it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/www.wmt.it\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/logo_wmt_blu_512x512.jpg\",\"contentUrl\":\"http:\\\/\\\/www.wmt.it\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/logo_wmt_blu_512x512.jpg\",\"width\":512,\"height\":512,\"caption\":\"W.M.T. - Water and Mechanical Technology s.r.l.\"},\"image\":{\"@id\":\"http:\\\/\\\/www.wmt.it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/pages\\\/WMT\\\/523330841079249?eid=ARBCva1bxbHrIwpLi2jUbikM5NzJrQOywcEqrkgUjYQ_m59R20SghP76Um2Ffw8jsoHFxRwr_28Y5a6v\",\"https:\\\/\\\/www.google.com\\\/maps\\\/place\\\/W.M.T.+-+Water+and+Mechanical+Technology+s.r.l.\\\/@45.538948,9.1806583,17z\\\/data=!3m1!4b1!4m5!3m4!1s0x4786bf60c912a84b:0xfc12749d2f8ea14a!8m2!3d45.538948!4d9.182847\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/2059941\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Separatori bifasici e trifasici, C.P.I. - Corrugate Plate Interceptor &#8226; W.M.T. - Water and Mechanical Technology s.r.l.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/www.wmt.it\/index.php\/separatori-bifasici-e-trifasici-c-p-i-corrugate-plate-interceptor\/","og_locale":"it_IT","og_type":"article","og_title":"Separatori bifasici e trifasici, C.P.I. - Corrugate Plate Interceptor &#8226; W.M.T. - Water and Mechanical Technology s.r.l.","og_description":"SEPARATORI A PACCHI LAMELLARI &#8211; C.P.I. Il separatore a pacchi lamellari, di seguito C.P.I., \u00e8 un dispositivo atto a separare particelle immiscibili contenute in un corpo fluido quando queste abbiano un diverso peso specifico rispetto al corpo fluido stesso. In tale evenienza i corpi fluidi multi-fase, solido-liquido o liquido-liquido, possono essere separati meccanicamente per effetto [&hellip;]","og_url":"http:\/\/www.wmt.it\/index.php\/separatori-bifasici-e-trifasici-c-p-i-corrugate-plate-interceptor\/","og_site_name":"W.M.T. - Water and Mechanical Technology s.r.l.","article_publisher":"https:\/\/www.facebook.com\/pages\/WMT\/523330841079249?eid=ARBCva1bxbHrIwpLi2jUbikM5NzJrQOywcEqrkgUjYQ_m59R20SghP76Um2Ffw8jsoHFxRwr_28Y5a6v","article_modified_time":"2025-03-06T15:13:43+00:00","og_image":[{"width":1892,"height":582,"url":"http:\/\/www.wmt.it\/wp-content\/uploads\/2025\/03\/cpi_front_image-2.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"7 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"http:\/\/www.wmt.it\/index.php\/separatori-bifasici-e-trifasici-c-p-i-corrugate-plate-interceptor\/","url":"http:\/\/www.wmt.it\/index.php\/separatori-bifasici-e-trifasici-c-p-i-corrugate-plate-interceptor\/","name":"Separatori bifasici e trifasici, C.P.I. - Corrugate Plate Interceptor &#8226; W.M.T. - Water and Mechanical Technology s.r.l.","isPartOf":{"@id":"http:\/\/www.wmt.it\/#website"},"primaryImageOfPage":{"@id":"http:\/\/www.wmt.it\/index.php\/separatori-bifasici-e-trifasici-c-p-i-corrugate-plate-interceptor\/#primaryimage"},"image":{"@id":"http:\/\/www.wmt.it\/index.php\/separatori-bifasici-e-trifasici-c-p-i-corrugate-plate-interceptor\/#primaryimage"},"thumbnailUrl":"http:\/\/www.wmt.it\/wp-content\/uploads\/2025\/03\/cpi_front_image-2.jpg","datePublished":"2025-03-05T15:21:21+00:00","dateModified":"2025-03-06T15:13:43+00:00","breadcrumb":{"@id":"http:\/\/www.wmt.it\/index.php\/separatori-bifasici-e-trifasici-c-p-i-corrugate-plate-interceptor\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["http:\/\/www.wmt.it\/index.php\/separatori-bifasici-e-trifasici-c-p-i-corrugate-plate-interceptor\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"http:\/\/www.wmt.it\/index.php\/separatori-bifasici-e-trifasici-c-p-i-corrugate-plate-interceptor\/#primaryimage","url":"http:\/\/www.wmt.it\/wp-content\/uploads\/2025\/03\/cpi_front_image-2.jpg","contentUrl":"http:\/\/www.wmt.it\/wp-content\/uploads\/2025\/03\/cpi_front_image-2.jpg","width":1892,"height":582,"caption":"File Name : DSCN0003.JPG File Size : 181.1KB (185430 Bytes) Date Taken : 0000\/00\/00 00:00:00 Image Size : 1024 x 768 pixels Resolution : 300 x 300 dpi Bit Depth : 8 bits\/channel Protection Attribute : Off Hide Attribute : Off Camera ID : N\/A Camera : E885 Quality Mode : NORMAL Metering Mode : Matrix Exposure Mode : Programmed Auto Speed Light : Yes Focal Length : 8 mm Shutter Speed : 1\/60 second Aperture : F2.8 Exposure Compensation : 0 EV White Balance : Auto Lens : Built-in Flash Sync Mode : Normal Exposure Difference : N\/A Flexible Program : N\/A Sensitivity : Auto Sharpening : Auto Image Type : Color Color Mode : N\/A Hue Adjustment : N\/A Saturation Control : Normal Tone Compensation : Auto Latitude(GPS) : N\/A Longitude(GPS) : N\/A Altitude(GPS) : N\/A"},{"@type":"BreadcrumbList","@id":"http:\/\/www.wmt.it\/index.php\/separatori-bifasici-e-trifasici-c-p-i-corrugate-plate-interceptor\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"http:\/\/www.wmt.it\/index.php\/en\/wmt-home\/"},{"@type":"ListItem","position":2,"name":"Separatori bifasici e trifasici, C.P.I. &#8211; Corrugate Plate Interceptor"}]},{"@type":"WebSite","@id":"http:\/\/www.wmt.it\/#website","url":"http:\/\/www.wmt.it\/","name":"W.M.T. - Water and Mechanical Technology s.r.l.","description":"ENGINEERING AND FILTERING SYSTEM, PURE WITH PROFIT","publisher":{"@id":"http:\/\/www.wmt.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/www.wmt.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"http:\/\/www.wmt.it\/#organization","name":"W.M.T. - Water and Mechanical Technology s.r.l.","url":"http:\/\/www.wmt.it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"http:\/\/www.wmt.it\/#\/schema\/logo\/image\/","url":"http:\/\/www.wmt.it\/wp-content\/uploads\/2019\/12\/logo_wmt_blu_512x512.jpg","contentUrl":"http:\/\/www.wmt.it\/wp-content\/uploads\/2019\/12\/logo_wmt_blu_512x512.jpg","width":512,"height":512,"caption":"W.M.T. - Water and Mechanical Technology s.r.l."},"image":{"@id":"http:\/\/www.wmt.it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/pages\/WMT\/523330841079249?eid=ARBCva1bxbHrIwpLi2jUbikM5NzJrQOywcEqrkgUjYQ_m59R20SghP76Um2Ffw8jsoHFxRwr_28Y5a6v","https:\/\/www.google.com\/maps\/place\/W.M.T.+-+Water+and+Mechanical+Technology+s.r.l.\/@45.538948,9.1806583,17z\/data=!3m1!4b1!4m5!3m4!1s0x4786bf60c912a84b:0xfc12749d2f8ea14a!8m2!3d45.538948!4d9.182847","https:\/\/www.linkedin.com\/company\/2059941"]}]}},"_links":{"self":[{"href":"http:\/\/www.wmt.it\/index.php\/wp-json\/wp\/v2\/pages\/3781","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.wmt.it\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"http:\/\/www.wmt.it\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"http:\/\/www.wmt.it\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.wmt.it\/index.php\/wp-json\/wp\/v2\/comments?post=3781"}],"version-history":[{"count":18,"href":"http:\/\/www.wmt.it\/index.php\/wp-json\/wp\/v2\/pages\/3781\/revisions"}],"predecessor-version":[{"id":3858,"href":"http:\/\/www.wmt.it\/index.php\/wp-json\/wp\/v2\/pages\/3781\/revisions\/3858"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.wmt.it\/index.php\/wp-json\/wp\/v2\/media\/3887"}],"wp:attachment":[{"href":"http:\/\/www.wmt.it\/index.php\/wp-json\/wp\/v2\/media?parent=3781"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}