{"id":599,"date":"2019-12-03T12:14:26","date_gmt":"2019-12-03T11:14:26","guid":{"rendered":"http:\/\/www2.wmt.it\/?page_id=599"},"modified":"2020-01-28T10:11:54","modified_gmt":"2020-01-28T09:11:54","slug":"trasporto-trucioli","status":"publish","type":"page","link":"http:\/\/www.wmt.it\/index.php\/trasporto-trucioli\/","title":{"rendered":"Trasporto trucioli"},"content":{"rendered":"\n<p>Progettiamo e realizziamo impianti di trasporto trucioli:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>A secco.<ul><li>Coclee.<\/li><li>Trasportatori raschianti.<\/li><li>Trasportatori a tapparelle.<\/li><li>Trasportatori a nastro in gomma.<\/li><li>Aste di spinta.<ul><li>Libere.<\/li><li>Guidate.<\/li><li>Vincolate.<ul><li>Rettilinee.<\/li><li>Curve.<\/li><\/ul><\/li><\/ul><\/li><\/ul><\/li><li>Ad umido.<ul><li>Interrati<ul><li>Canali idrici.<\/li><li>Canali misti idrico meccanici.<\/li><\/ul><\/li><li>Aerei<ul><li>Stazioni di rilancio con pompaggio in pressione.<\/li><li>Stazioni di rilancio con pompaggio&nbsp;a pelo libero.<\/li><li>Stazioni di rilancio con pompaggio&nbsp;ad accumulo.<\/li><\/ul><\/li><\/ul><\/li><\/ul>\n\n\n\n<table style=\"width: 100%;\" cellspacing=\"0\" border=\"0\">\n<tbody>\n<tr><\/tr>\n<tr>\n<td style=\"width: 10%;\" align=\"center\"><\/td>\n<td style=\"width: 35%;\" align=\"center\"><div class=\"wp-block-button\"><a class=\"wp-block-button__link has-background has-vivid-cyan-blue-background-color\" href=\"http:\/\/www.wmt.it\/index.php\/trasporto-trucioli-foto\/\" target=\"_blank\" rel=\"noopener noreferrer\">Galleria immagini<\/a><\/div><\/td>\n<td style=\"width: 10%;\" align=\"center\"><\/td>\n<td style=\"width: 35%;\" align=\"center\"><\/td>\n<td style=\"width: 10%;\" align=\"center\"><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Progettiamo e realizziamo impianti di trasporto trucioli: A secco. Coclee. Trasportatori raschianti. Trasportatori a tapparelle. Trasportatori a nastro in gomma. Aste di spinta. Libere. Guidate. Vincolate. Rettilinee. Curve. Ad umido. Interrati Canali idrici. Canali misti idrico meccanici. Aerei Stazioni di rilancio con pompaggio in pressione. Stazioni di rilancio con pompaggio&nbsp;a pelo libero. Stazioni di rilancio [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":1726,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"ngg_post_thumbnail":0,"footnotes":""},"class_list":["post-599","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Trasporto trucioli &#8226; W.M.T. - Water and Mechanical Technology s.r.l.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/www.wmt.it\/index.php\/trasporto-trucioli\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Trasporto trucioli &#8226; W.M.T. - Water and Mechanical Technology s.r.l.\" \/>\n<meta property=\"og:description\" content=\"Progettiamo e realizziamo impianti di trasporto trucioli: A secco. Coclee. Trasportatori raschianti. Trasportatori a tapparelle. Trasportatori a nastro in gomma. Aste di spinta. Libere. Guidate. Vincolate. Rettilinee. Curve. Ad umido. Interrati Canali idrici. Canali misti idrico meccanici. Aerei Stazioni di rilancio con pompaggio in pressione. Stazioni di rilancio con pompaggio&nbsp;a pelo libero. Stazioni di rilancio [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"http:\/\/www.wmt.it\/index.php\/trasporto-trucioli\/\" \/>\n<meta property=\"og:site_name\" content=\"W.M.T. - Water and Mechanical Technology s.r.l.\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/pages\/WMT\/523330841079249?eid=ARBCva1bxbHrIwpLi2jUbikM5NzJrQOywcEqrkgUjYQ_m59R20SghP76Um2Ffw8jsoHFxRwr_28Y5a6v\" \/>\n<meta property=\"article:modified_time\" content=\"2020-01-28T09:11:54+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.wmt.it\/wp-content\/uploads\/2019\/12\/trucioli-e1576660559809.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/www.wmt.it\\\/index.php\\\/trasporto-trucioli\\\/\",\"url\":\"http:\\\/\\\/www.wmt.it\\\/index.php\\\/trasporto-trucioli\\\/\",\"name\":\"Trasporto trucioli &#8226; W.M.T. - Water and Mechanical Technology s.r.l.\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/www.wmt.it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\\\/\\\/www.wmt.it\\\/index.php\\\/trasporto-trucioli\\\/#primaryimage\"},\"image\":{\"@id\":\"http:\\\/\\\/www.wmt.it\\\/index.php\\\/trasporto-trucioli\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.wmt.it\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/trucioli-e1576660559809.jpg\",\"datePublished\":\"2019-12-03T11:14:26+00:00\",\"dateModified\":\"2020-01-28T09:11:54+00:00\",\"breadcrumb\":{\"@id\":\"http:\\\/\\\/www.wmt.it\\\/index.php\\\/trasporto-trucioli\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/www.wmt.it\\\/index.php\\\/trasporto-trucioli\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"http:\\\/\\\/www.wmt.it\\\/index.php\\\/trasporto-trucioli\\\/#primaryimage\",\"url\":\"http:\\\/\\\/www.wmt.it\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/trucioli-e1576660559809.jpg\",\"contentUrl\":\"http:\\\/\\\/www.wmt.it\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/trucioli-e1576660559809.jpg\",\"width\":1920,\"height\":600},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/www.wmt.it\\\/index.php\\\/trasporto-trucioli\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"http:\\\/\\\/www.wmt.it\\\/index.php\\\/en\\\/wmt-home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Trasporto trucioli\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/www.wmt.it\\\/#website\",\"url\":\"http:\\\/\\\/www.wmt.it\\\/\",\"name\":\"W.M.T. - Water and Mechanical Technology s.r.l.\",\"description\":\"ENGINEERING AND FILTERING SYSTEM, PURE WITH PROFIT\",\"publisher\":{\"@id\":\"http:\\\/\\\/www.wmt.it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/www.wmt.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"http:\\\/\\\/www.wmt.it\\\/#organization\",\"name\":\"W.M.T. - Water and Mechanical Technology s.r.l.\",\"url\":\"http:\\\/\\\/www.wmt.it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"http:\\\/\\\/www.wmt.it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/www.wmt.it\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/logo_wmt_blu_512x512.jpg\",\"contentUrl\":\"http:\\\/\\\/www.wmt.it\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/logo_wmt_blu_512x512.jpg\",\"width\":512,\"height\":512,\"caption\":\"W.M.T. - Water and Mechanical Technology s.r.l.\"},\"image\":{\"@id\":\"http:\\\/\\\/www.wmt.it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/pages\\\/WMT\\\/523330841079249?eid=ARBCva1bxbHrIwpLi2jUbikM5NzJrQOywcEqrkgUjYQ_m59R20SghP76Um2Ffw8jsoHFxRwr_28Y5a6v\",\"https:\\\/\\\/www.google.com\\\/maps\\\/place\\\/W.M.T.+-+Water+and+Mechanical+Technology+s.r.l.\\\/@45.538948,9.1806583,17z\\\/data=!3m1!4b1!4m5!3m4!1s0x4786bf60c912a84b:0xfc12749d2f8ea14a!8m2!3d45.538948!4d9.182847\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/2059941\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Trasporto trucioli &#8226; W.M.T. - Water and Mechanical Technology s.r.l.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/www.wmt.it\/index.php\/trasporto-trucioli\/","og_locale":"it_IT","og_type":"article","og_title":"Trasporto trucioli &#8226; W.M.T. - Water and Mechanical Technology s.r.l.","og_description":"Progettiamo e realizziamo impianti di trasporto trucioli: A secco. Coclee. Trasportatori raschianti. Trasportatori a tapparelle. Trasportatori a nastro in gomma. Aste di spinta. Libere. Guidate. Vincolate. Rettilinee. Curve. Ad umido. Interrati Canali idrici. Canali misti idrico meccanici. Aerei Stazioni di rilancio con pompaggio in pressione. Stazioni di rilancio con pompaggio&nbsp;a pelo libero. Stazioni di rilancio [&hellip;]","og_url":"http:\/\/www.wmt.it\/index.php\/trasporto-trucioli\/","og_site_name":"W.M.T. - Water and Mechanical Technology s.r.l.","article_publisher":"https:\/\/www.facebook.com\/pages\/WMT\/523330841079249?eid=ARBCva1bxbHrIwpLi2jUbikM5NzJrQOywcEqrkgUjYQ_m59R20SghP76Um2Ffw8jsoHFxRwr_28Y5a6v","article_modified_time":"2020-01-28T09:11:54+00:00","og_image":[{"width":1920,"height":600,"url":"http:\/\/www.wmt.it\/wp-content\/uploads\/2019\/12\/trucioli-e1576660559809.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"http:\/\/www.wmt.it\/index.php\/trasporto-trucioli\/","url":"http:\/\/www.wmt.it\/index.php\/trasporto-trucioli\/","name":"Trasporto trucioli &#8226; W.M.T. - Water and Mechanical Technology s.r.l.","isPartOf":{"@id":"http:\/\/www.wmt.it\/#website"},"primaryImageOfPage":{"@id":"http:\/\/www.wmt.it\/index.php\/trasporto-trucioli\/#primaryimage"},"image":{"@id":"http:\/\/www.wmt.it\/index.php\/trasporto-trucioli\/#primaryimage"},"thumbnailUrl":"http:\/\/www.wmt.it\/wp-content\/uploads\/2019\/12\/trucioli-e1576660559809.jpg","datePublished":"2019-12-03T11:14:26+00:00","dateModified":"2020-01-28T09:11:54+00:00","breadcrumb":{"@id":"http:\/\/www.wmt.it\/index.php\/trasporto-trucioli\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["http:\/\/www.wmt.it\/index.php\/trasporto-trucioli\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"http:\/\/www.wmt.it\/index.php\/trasporto-trucioli\/#primaryimage","url":"http:\/\/www.wmt.it\/wp-content\/uploads\/2019\/12\/trucioli-e1576660559809.jpg","contentUrl":"http:\/\/www.wmt.it\/wp-content\/uploads\/2019\/12\/trucioli-e1576660559809.jpg","width":1920,"height":600},{"@type":"BreadcrumbList","@id":"http:\/\/www.wmt.it\/index.php\/trasporto-trucioli\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"http:\/\/www.wmt.it\/index.php\/en\/wmt-home\/"},{"@type":"ListItem","position":2,"name":"Trasporto trucioli"}]},{"@type":"WebSite","@id":"http:\/\/www.wmt.it\/#website","url":"http:\/\/www.wmt.it\/","name":"W.M.T. - Water and Mechanical Technology s.r.l.","description":"ENGINEERING AND FILTERING SYSTEM, PURE WITH PROFIT","publisher":{"@id":"http:\/\/www.wmt.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/www.wmt.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"http:\/\/www.wmt.it\/#organization","name":"W.M.T. - Water and Mechanical Technology s.r.l.","url":"http:\/\/www.wmt.it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"http:\/\/www.wmt.it\/#\/schema\/logo\/image\/","url":"http:\/\/www.wmt.it\/wp-content\/uploads\/2019\/12\/logo_wmt_blu_512x512.jpg","contentUrl":"http:\/\/www.wmt.it\/wp-content\/uploads\/2019\/12\/logo_wmt_blu_512x512.jpg","width":512,"height":512,"caption":"W.M.T. - Water and Mechanical Technology s.r.l."},"image":{"@id":"http:\/\/www.wmt.it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/pages\/WMT\/523330841079249?eid=ARBCva1bxbHrIwpLi2jUbikM5NzJrQOywcEqrkgUjYQ_m59R20SghP76Um2Ffw8jsoHFxRwr_28Y5a6v","https:\/\/www.google.com\/maps\/place\/W.M.T.+-+Water+and+Mechanical+Technology+s.r.l.\/@45.538948,9.1806583,17z\/data=!3m1!4b1!4m5!3m4!1s0x4786bf60c912a84b:0xfc12749d2f8ea14a!8m2!3d45.538948!4d9.182847","https:\/\/www.linkedin.com\/company\/2059941"]}]}},"_links":{"self":[{"href":"http:\/\/www.wmt.it\/index.php\/wp-json\/wp\/v2\/pages\/599","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.wmt.it\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"http:\/\/www.wmt.it\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"http:\/\/www.wmt.it\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"http:\/\/www.wmt.it\/index.php\/wp-json\/wp\/v2\/comments?post=599"}],"version-history":[{"count":3,"href":"http:\/\/www.wmt.it\/index.php\/wp-json\/wp\/v2\/pages\/599\/revisions"}],"predecessor-version":[{"id":2695,"href":"http:\/\/www.wmt.it\/index.php\/wp-json\/wp\/v2\/pages\/599\/revisions\/2695"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.wmt.it\/index.php\/wp-json\/wp\/v2\/media\/1726"}],"wp:attachment":[{"href":"http:\/\/www.wmt.it\/index.php\/wp-json\/wp\/v2\/media?parent=599"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}